{"id":3898,"date":"2017-09-19T12:17:25","date_gmt":"2017-09-19T12:17:25","guid":{"rendered":"http:\/\/www.ciencianews.com.br\/?page_id=3898"},"modified":"2020-07-28T15:23:58","modified_gmt":"2020-07-28T15:23:58","slug":"homologacao_pagina_inicial_19_09_17","status":"publish","type":"page","link":"https:\/\/www.ciencianews.com.br\/index.php\/homologacao_pagina_inicial_19_09_17\/","title":{"rendered":"homologacao_pagina_inicial"},"content":{"rendered":"<h1 align=\"center\"><span style=\"color: #000000;\"><strong>Academia de Ci\u00eancia e Tecnologia<\/strong><\/span><\/h1>\n<h3 style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a title=\"AC&amp;T \u2013 Instituto de P\u00f3s Gradua\u00e7\u00e3o nas \u00c1reas Biol\u00f3gicas\" href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/act-instituto-de-pos-graduacao-nas-areas-biologicas\/\"><strong>Instituto de P\u00f3s Gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas e Hematol\u00f3gicas<\/strong><\/a><\/span><\/h3>\n<\/p>\n<h3 style=\"text-align: center; color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Cursos de P\u00f3s Gradua\u00e7\u00e3o Lato-Sensu<\/strong><\/a><\/span><\/h3>\n<div style=\"text-align: center;\">\n<p><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/publicacoes\/no-you-tube\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/04\/youtube.jpg\" alt=\"youtube\" width=\"235\" height=\"30\" class=\"alignnone size-full wp-image-4087\" \/><\/a><a href=\"https:\/\/www.facebook.com\/Academia-de-Ci\u00eancia-e-Tecnologia-173959839754175\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/01\/facebook-30x30ligue2.png\" alt=\"facebook-30x30ligue2\" width=\"209\" height=\"30\" class=\"alignnone size-full wp-image-3978\" \/><\/a><a href=\"https:\/\/www.instagram.com\/academia.ciencia.tecnologia\/?utm_source=ig_profile_share&#038;igshid=1i17f68xjakkz\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/11\/instagram2.png\" alt=\"instagram2\" width=\"199\" height=\"29\" class=\"alignnone size-full wp-image-4888\" \/><\/a><a href=\"https:\/\/api.whatsapp.com\/send?phone=5517997944667&#038;text=Ol%C3%A1%2C%20tudo%20bem%20%3F\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2013\/07\/whatsapp.jpg\" width=\"164\" height=\"30\" class=\"alignnone size-full wp-image-4796\" \/><\/a><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/imagens-cientificas\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/imagens_cientificas2.png\" alt=\"chat\" width=\"228\" height=\"30\" class=\"alignnone size-full wp-image-4034\" \/><br \/>\n<\/a><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator.png\" alt=\"separator\" width=\"665\" height=\"29\" class=\"alignnone size-full wp-image-5763\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator.png 665w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-300x13.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-500x22.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-250x11.png 250w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/p>\n<h3 align=\"center\"><span style=\"color: #000000;text-decoration: underline\"><strong>Conte\u00fado de responsabilidade dos idealizadores:<\/strong><\/span><\/h1>\n<h4 style=\"text-align: center;\"><span><strong>Diretor Cient\u00edfico: Prof. Dr. Paulo Cesar Naoum<\/strong><\/span><\/h3>\n<h4 style=\"text-align: center;\"><span><strong>Diretor Cl\u00ednico: Prof .Dr. Flavio Augusto Naoum<\/strong><\/span><\/h3>\n<h4 style=\"text-align: center;\"><span><strong>Diretora Pedag\u00f3gica: Profa. Ms .Alia M.F. Naoum<\/strong><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator.png\" alt=\"separator\" width=\"665\" height=\"29\" class=\"alignnone size-full wp-image-5763\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator.png 665w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-300x13.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-500x22.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-250x11.png 250w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><br \/>\n<\/DIV><!--Congresso virtual de analise clinica--><\/p>\n<div style=\"text-align: center;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/01\/congresso-analise-clinica.png\" alt=\"congresso-analise-clinica\" width=\"869\" height=\"200\" class=\"alignnone size-full wp-image-5885\" \/>\n<\/div>\n<div style=\"font-size: 18px; text-align: center; color: #000000 ; font-weight: bold\">FOCO EM HEMATOLOGIA, BANCO DE SANGUE E MICROBIOLOGIA<\/div>\n<p>\n[ezcol_1half]<\/p>\n<div style=\"font-size: 15px; color: #000000;text-align: justify;\">\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Conte\u00fado program\u00e1tico: <\/div>\n<ul>\n<li>Aulas \u201con demand\u201d (gravadas, com mais de 20 temas).<\/li>\n<li>Aulas ao vivo (de 14 a 18 de setembro, das 19h00 \u00e0s 20h00).<\/li>\n<li>Microsc\u00f3pio virtual (an\u00e1lise de l\u00e2minas em tempo real).<\/li>\n<li>Certificado ao final do curso.<\/li>\n<\/ul>\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Per\u00edodo: <\/div>\n<p>14 a 21 de setembro de 2020.  <\/p>\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Coordena\u00e7\u00e3o: <\/div>\n<p>Prof. Dr. Fl\u00e1vio Augusto Naoum e Prof. Dr. Paulo Cesar Naoum.<\/p>\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Investimento: <\/div>\n<p> R$100,00.<br \/>\n<!-- INICIO DO BOTAO PAGSEGURO --><a href=\"https:\/\/pag.ae\/7WaZhnbw6\/button\" target=\"_blank\" title=\"Pagar com PagSeguro\"><img decoding=\"async\" src=\"\/\/assets.pagseguro.com.br\/ps-integration-assets\/botoes\/pagamentos\/160x20-pagar.gif\" alt=\"Pague com PagSeguro - \u00e9 r\u00e1pido, gr\u00e1tis e seguro!\" \/><\/a><!-- FIM DO BOTAO PAGSEGURO -->\n<\/div>\n<p>[\/ezcol_1half]<br \/>\n[ezcol_1half_end]<\/p>\n<div style=\"color: #000000; text-align: center;font-size: 15px;font-weight: bold;background-color: #C0C0C0;right: 100px; width: 100%\">Fa\u00e7a aqui sua inscri\u00e7\u00e3o<\/div>\n<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5887-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5887\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/3898#wpcf7-f5887-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5887\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5887-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p>Seu nome (obrigat\u00f3rio)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>Seu e-mail (obrigat\u00f3rio)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p>Telefone (obrigat\u00f3rio)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-142\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tel-142\" \/><\/span>\n<\/p>\n\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"229\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<br \/>\n[\/ezcol_1half_end]<\/p>\n<div style=\"font-size: 15px; text-align: center; color: #000000 ; font-weight: bold\">Dados para dep\u00f3sitos ou transfer\u00eancias: Banco Santander. Ag:0434 C\/C:13005960-1 (\u00e9 necess\u00e1rio enviar comprovante para a.c.t@terra.com.br) ou <a href=\"https:\/\/api.whatsapp.com\/send?phone=5517997944667&#038;text=Ol%C3%A1%2C%20sobre%20o%20CONGRESSO%20VIRTUAL%20DE%20AN%C3%81LISES%20CL%C3%8DNICAS\" >WhatsApp (17) 9979-44667(clique aqui)<\/a><\/div>\n<p><\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/menu_pos_latosensu.png\" alt=\"Curso de P\u00f3s Gradua\u00e7\u00e3o em Hematologia e Banco de Sangue\" title = \"Curso de P\u00f3s Gradua\u00e7\u00e3o em Hematologia e Banco de Sangue\" width=\"869\" height=\"100\" class=\"alignnone size-full wp-image-4748\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/menu_pos_latosensu.png 869w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/menu_pos_latosensu-300x35.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/menu_pos_latosensu-250x29.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/menu_pos_latosensu-680x78.png 680w\" sizes=\"auto, (max-width: 869px) 100vw, 869px\" \/>\n<\/div>\n<div style=\"text-align: left;\">\n<div style=\"text-align: left;\">\n<div style=\"font-size: 25px; text-align: center; color: #000000 ;background-color: #FF7F50; font-weight: bold\">HEMATOLOGIA LABORATORIAL E CL\u00cdNICA<\/div>\n<div style=\"font-size: 18px; text-align: center; color: #000000 ; font-weight: bold\">CURSO DE ESPECIALIZA\u00c7\u00c3O TE\u00d3RICO-PR\u00c1TICO EM 14 MESES<\/div>\n<p>\n&nbsp;<\/p>\n<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/hematologia-laboratorial-e-clinica1.png\" alt=\"hematologia-laboratorial-e-clinica\" width=\"600\" height=\"286\" class=\"alignnone size-full wp-image-5928\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/hematologia-laboratorial-e-clinica1.png 600w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/hematologia-laboratorial-e-clinica1-300x143.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/hematologia-laboratorial-e-clinica1-500x238.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/hematologia-laboratorial-e-clinica1-250x119.png 250w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>\n<div style=\"font-size: 25px; text-align: center; color: #000000 ;background-color: #FFDAB9; font-weight: bold\">Transferido para Fevereiro\/2021, com <u>NOVO FORMATO DE ENSINO<\/u>  <\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator.png\" alt=\"separator\" width=\"665\" height=\"29\" class=\"alignnone size-full wp-image-5763\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator.png 665w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-300x13.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-500x22.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-250x11.png 250w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/div>\n<p>&nbsp;<\/p>\n<div style=\"font-size: 25px; text-align: center; color: #000000 ;background-color: #FF7F50; font-weight: bold\">MICROBIOLOGIA, MICOLOGIA E VIROLOGIA LABORATORIAL E HOSPITALAR<\/div>\n<div style=\"font-size: 18px; text-align: center; color: #000000 ; font-weight: bold\">CURSO DE ESPECIALIZA\u00c7\u00c3O TE\u00d3RICO-PR\u00c1TICO EM 14 MESES<\/div>\n<p>\n&nbsp;<\/p>\n<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/Curso-de-Microbiologia-Fev2021.png\" alt=\"Curso-de-Microbiologia-Fev2021\" width=\"600\" height=\"315\" class=\"alignnone size-full wp-image-5929\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/Curso-de-Microbiologia-Fev2021.png 600w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/Curso-de-Microbiologia-Fev2021-300x158.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/Curso-de-Microbiologia-Fev2021-500x263.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/Curso-de-Microbiologia-Fev2021-250x131.png 250w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <\/div>\n<div style=\"font-size: 25px; text-align: center; color: #000000 ;background-color: #FFDAB9; font-weight: bold\">Transferido para Fevereiro\/2021, com <u>NOVO FORMATO DE ENSINO<\/u>  <\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator.png\" alt=\"separator\" width=\"665\" height=\"29\" class=\"alignnone size-full wp-image-5763\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator.png 665w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-300x13.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-500x22.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/separator-250x11.png 250w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/div>\n<p>&nbsp;<\/p>\n<p>[ezcol_2third]<\/p>\n<div style=\"font-size: 25px; text-align: center; color: #000000 ;background-color: #FF7F50; font-weight: bold\">P\u00d3S GRADUA\u00c7\u00c3O<BR>UROPROCTOLOGIA E OBSTETR\u00cdCIA <\/div>\n<div style=\"font-size: 18px; text-align: center; color: #000000 ; font-weight: bold\">CURSO TE\u00d3RICO-PR\u00c1TICO<\/div>\n<div style=\"font-size: 15px; color: #000000;text-align: justify;\">\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> In\u00edcio: <\/div>\n<p> Outubro de 2020 \u2013 T\u00e9rmino: Novembro de 2021.<\/p>\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Carga Hor\u00e1ria: <\/div>\n<p> 360 horas.<\/p>\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Modelo do Curso: <\/div>\n<ul>\n<li>Aulas te\u00f3ricas presenciais mensais;<\/li>\n<li>Aulas demonstrativas;<\/li>\n<li>Aulas pr\u00e1ticas entre alunas;<\/li>\n<li>Aulas pr\u00e1ticas com pacientes;<\/li>\n<li>Material online para estudo (incluindo metodologia cient\u00edfica);<\/li>\n<li>TCC sob a forma de artigo cient\u00edfico.<\/li>\n<\/ul>\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Certifica\u00e7\u00e3o: <\/div>\n<p> Credenciado pelo MEC e com as chancelas da AC&#038;T e FACULDADE DE MEDICINA FACERES de S\u00e3o Jos\u00e9 do Rio Preto.  <\/p>\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Facilidades: <\/div>\n<p> Acomoda\u00e7\u00f5es gratuitas em FLATS masculino e feminino da AC&#038;T durante todo o per\u00edodo do curso, transportes em vans dos FLATS \u00e0 AC&#038;T, caf\u00e9 da manh\u00e3 nos s\u00e1bados e domingos,  coffe-breaks em intervalos de aulas, e aulas online disponibilizadas nesta homepage durante toda a dura\u00e7\u00e3o do curso.<\/p>\n<div style=\"font-style: italic;font-size: 16px; color: #000000; font-weight: bold\"> Investimento: <\/div>\n<p> 15 parcelas mensais de R$560,00 (quinhentos e sessenta reais).<\/p><\/div>\n<div style=\"color: #0101DF; text-align: center;font-size: 15px;font-weight: bold;background-color: #FFDAB9;right: 100px; width: 100%\"><a href=\"https:\/\/www.anapaulagallonaoum.com.br\/cursos\/pos-graduacao-em-uroginecologia-e-obstetricia\/\" target=\"_blank\">PROGRAMA\u00c7\u00c3O COMPLETA E OUTRAS INFORMA\u00c7\u00d5ES: CLIQUE AQUI<\/a><\/div>\n<p>[\/ezcol_2third]<br \/>\n[ezcol_1third_end]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/UROPROCTOLOGIA-E-OBSTETRICIA.jpg\" alt=\"UROPROCTOLOGIA-E-OBSTETRICIA\" width=\"280\" height=\"590\" class=\"alignnone size-full wp-image-5856\" \/><\/p>\n<p>[\/ezcol_1third_end]<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: left;\">\n[ezcol_1third]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/Imagem11.jpg\" alt=\"Imagem1\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5781\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\">DIA DE CURSO NA AC&#038;T<\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/Imagem2.jpg\" alt=\"Imagem2\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5782\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\">LABORAT\u00d3RIO DE AN\u00c1LISES DE RESULTADOS DE EXAMES<\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third_end]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/Imagem31.jpg\" alt=\"Imagem3\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5783\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\">LABORAT\u00d3RIO DE CITOHEMATOLOGIA<\/div>\n<p>[\/ezcol_1third_end]\n<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><!--\nbiblioteca digital\n--><\/p>\n<div style=\"text-align: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/bliblioteca-digital.png\" alt=\"bliblioteca-digital\" width=\"948\" height=\"107\" class=\"alignnone size-full wp-image-5050\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/bliblioteca-digital.png 948w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/bliblioteca-digital-300x34.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/bliblioteca-digital-500x56.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/bliblioteca-digital-250x28.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/bliblioteca-digital-680x77.png 680w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/bliblioteca-digital-940x106.png 940w\" sizes=\"auto, (max-width: 948px) 100vw, 948px\" \/>\n<\/div>\n<div style=\"color: #000000; text-align: center; font-size: 15px; font-weight: bold;\">\nEditores: Paulo Cesar Naoum e Fl\u00e1vio Augusto Naoum | Compilador: Bruno Felix Bezerra | Composi\u00e7\u00e3o: Renan Salenave Troiano\n<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\">\n<p>[ezcol_1third]<br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/biblioteca_digital\/biblioteca-digital-hematologia\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal1-150x150.png\" alt=\"principal1\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-5051\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal1-150x150.png 150w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal1-300x300.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal1-500x500.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal1-250x250.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal1-680x680.png 680w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal1-940x940.png 940w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal1.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n<div style=\"color: #000000; text-align: center; font-size: 15px; font-weight: bold;\">HEMATOLOGIA<\/a><\/p>\n<\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third]<br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/biblioteca_digital\/biblioteca-digital-hemoterapia\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/hemoterapia-150x150.png\" alt=\"hemoterapia\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-5005\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/hemoterapia-150x150.png 150w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/hemoterapia-300x300.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/hemoterapia-500x500.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/hemoterapia-250x250.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/hemoterapia-680x680.png 680w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/hemoterapia-940x940.png 940w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/hemoterapia.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n<div style=\"color: #000000; text-align: center; font-size: 15px; font-weight: bold;\">HEMOTERAPIA<\/a><\/p>\n<\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third_end]<br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/biblioteca_digital\/biblioteca-digital-microbiologia\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/microbiologia-150x150.png\" alt=\"microbiologia\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-5006\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/microbiologia-150x150.png 150w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/microbiologia-300x300.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/microbiologia-500x500.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/microbiologia-250x250.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/microbiologia-680x680.png 680w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/microbiologia-940x940.png 940w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/microbiologia.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n<div style=\"color: #000000; text-align: center; font-size: 15px; font-weight: bold;\">MICROBIOLOGIA<\/a><\/p>\n<\/div>\n<p>[\/ezcol_1third_end]<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\">\n<p>[ezcol_1third]<br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/biblioteca_digital\/biblioteca-digital-bioquimica-clinica\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/subtema3-150x150.png\" alt=\"subtema3\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-5011\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/subtema3-150x150.png 150w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/subtema3-300x300.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/subtema3-500x500.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/subtema3-250x250.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/subtema3-680x680.png 680w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/subtema3-940x940.png 940w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/subtema3.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/> <\/p>\n<div style=\"color: #000000; text-align: center; font-size: 15px; font-weight: bold;\">BIOQU\u00cdMICA CL\u00cdNICA<\/a><\/p>\n<\/div>\n<p>[\/ezcol_1third]<\/p>\n<p>[ezcol_1third]<br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/biblioteca_digital\/b-d-imunohematologia\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal5-150x150.png\" alt=\"principal5\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-5052\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal5-150x150.png 150w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal5-300x300.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal5-500x500.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal5-250x250.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal5-680x680.png 680w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal5-940x940.png 940w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal5.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/> <\/p>\n<div style=\"color: #000000; text-align: center; font-size: 15px; font-weight: bold;\">IMUNOHEMATOLOGIA<\/a><\/p>\n<\/div>\n<p>[\/ezcol_1third]<\/p>\n<p>[ezcol_1third_end]<br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/biblioteca_digital\/b-d-outros-temas\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal6-150x150.png\" alt=\"principal6\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-5053\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal6-150x150.png 150w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal6-300x300.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal6-500x500.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal6-250x250.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal6-680x680.png 680w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal6-940x940.png 940w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2019\/08\/principal6.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n<div style=\"color: #000000; text-align: center; font-size: 15px; font-weight: bold;\">OUTROS TEMAS<\/a><\/p>\n<\/div>\n<p>[\/ezcol_1third_end]<\/p>\n<\/div>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p><!--\nparte 3\n--><\/p>\n<div style=\"text-align: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/livros-online-acesso-gratuito3.png\" alt=\"livros-online-acesso-gratuito3\" width=\"893\" height=\"66\" class=\"alignnone size-full wp-image-4925\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/livros-online-acesso-gratuito3.png 893w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/livros-online-acesso-gratuito3-300x22.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/livros-online-acesso-gratuito3-500x37.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/livros-online-acesso-gratuito3-250x18.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/livros-online-acesso-gratuito3-680x50.png 680w\" sizes=\"auto, (max-width: 893px) 100vw, 893px\" \/>\n<\/div>\n<div style=\"text-align: left;\">\n[ezcol_1quarter]<\/p>\n<p><a href=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/12\/lvr_1_lin_31.png\" rel=\u201dlightbox\u201d data-lightbox-type=\u201diframe\u201d  rel=\"lightbox-0\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/12\/lvr_1_lin_3.png\" alt=\"lvr_3_lin_1\" width=\"200\" height=\"160\" \/><\/a><br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/arquivos\/ACET\/IMAGENS\/doenca_dos_eritrocitos\/doenca_dos_eritrocitos_o_eritrocito.pdf\" target=\"_blank\"> <\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\">DOEN\u00c7A DOS ERITR\u00d3CITOS <\/a>\n<\/div>\n<p>[\/ezcol_1quarter]<br \/>\n[ezcol_1quarter]<\/p>\n<p><a href=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/12\/lvr_1_lin_21.png\" rel=\u201dlightbox\u201d data-lightbox-type=\u201diframe\u201d  rel=\"lightbox-1\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/12\/lvr_1_lin_2.png\" alt=\"lvr_3_lin_1\" width=\"195\" height=\"160\" \/><\/a><br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/arquivos\/ACET\/IMAGENS\/livros\/acesso_gratuito\/Livro_completo - Hematologia Eritrocitos.pdf\" target=\"_blank\"> <\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\">HEMATOLOGIA LABORATORIAL DOS ERITR\u00d3CITOS <\/a>\n<\/div>\n<p>[\/ezcol_1quarter]<br \/>\n[ezcol_1quarter]<\/p>\n<p><a href=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/12\/lvr_2_lin_11.png\" rel=\u201dlightbox\u201d data-lightbox-type=\u201diframe\u201d  rel=\"lightbox-2\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/12\/lvr_2_lin_1.png\" alt=\"lvr_3_lin_1\" width=\"195\" height=\"160\" \/><\/a><br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/arquivos\/ACET\/IMAGENS\/livros\/acesso_gratuito\/Livro_completo - doencas-que-alteram-o-exame-bioquimico.pdf\" target=\"_blank\"> <\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\">DOEN\u00c7AS QUE ALTERAM OS EXAMES BIOQUIMICOS <\/a>\n<\/div>\n<p>[\/ezcol_1quarter]<br \/>\n[ezcol_1quarter_end]<\/p>\n<p><a href=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/12\/lvr_3_lin_11.png\" rel=\u201dlightbox\u201d data-lightbox-type=\u201diframe\u201d  rel=\"lightbox-3\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/12\/lvr_3_lin_1.png\" alt=\"lvr_3_lin_1\" width=\"200\" height=\"160\" \/><\/a><br \/>\n<a href=\"http:\/\/www.ciencianews.com.br\/arquivos\/ACET\/IMAGENS\/livros\/acesso_gratuito\/Livro_completo - Eletroforese.pdf\" target=\"_blank\"> <\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\">ELETROFORESES DE HEMOGLOBINAS, PROTE\u00cdNAS, LIPO E DNA <\/a>\n<\/div>\n<p>[\/ezcol_1quarter_end]<\/p>\n<\/div>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p><!--\nparte 4\n--><\/p>\n<div style=\"text-align: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas_cases_hematologia_menu.png\" alt=\"atlas_cases_hematologia_menu\" width=\"862\" height=\"60\" class=\"alignnone size-full wp-image-5540\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas_cases_hematologia_menu.png 862w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas_cases_hematologia_menu-300x21.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas_cases_hematologia_menu-500x35.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas_cases_hematologia_menu-250x17.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas_cases_hematologia_menu-680x47.png 680w\" sizes=\"auto, (max-width: 862px) 100vw, 862px\" \/>\n<\/div>\n<div style=\"text-align: left;\">\n[ezcol_1third]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas-cases-leucocitos-img.png\" alt=\"atlas-cases-leucocitos-img\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5543\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/atlas-e-cases-de-leucocitos-anormais\/\">ATLAS E CASES DE LEUC\u00d3CITOS ANORMAIS<\/a><\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas-cases-leucemia-img.png\" alt=\"atlas-cases-leucemia-img\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5542\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/atlas-e-cases-de-leucemias-linfoma-e-mieloma\/\" >ATLAS E CASES DE LEUCEMIAS, LINFOMA E MIELOMA<\/a><\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third_end]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/atlas-cases-anemias-img.png\" alt=\"atlas-cases-anemias-img\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5541\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/atlas-e-cases-de-anemias\/\">ATLAS E CASES DE ANEMIAS<\/a><\/div>\n<p>[\/ezcol_1third_end]<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p><!--\nparte 5\n--><\/p>\n<div style=\"text-align: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-menu.png\" alt=\"quickclass-menu\" width=\"868\" height=\"110\" class=\"alignnone size-full wp-image-5546\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-menu.png 868w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-menu-300x38.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-menu-500x63.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-menu-250x32.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-menu-680x86.png 680w\" sizes=\"auto, (max-width: 868px) 100vw, 868px\" \/>\n<\/div>\n<div style=\"text-align: left;\">\n[ezcol_1third]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img1.png\" alt=\"quickclass-img1\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5548\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img1.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img1-250x132.png 250w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/quick-class-anemias-aulas-rapidas-de-3-a-8-minutos\/\">DEFINI\u00c7\u00c3O E CLASSIFICA\u00c7\u00c3O<\/a><\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img2.png\" alt=\"quickclass-img2\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5549\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img2.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img2-250x132.png 250w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/quick-class-anemias-aulas-rapidas-de-3-a-8-minutos\/\" target=\"_blank\">\u00cdNDICES HEMATIM\u00c9TRICOS<\/a><\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third_end]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img3.png\" alt=\"quickclass-img3\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-5550\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img3.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/quickclass-img3-250x132.png 250w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/quick-class-anemias-aulas-rapidas-de-3-a-8-minutos\/\" target=\"_blank\">ANEMIAS ADQUIRIDAS<\/a><\/div>\n<p>[\/ezcol_1third_end]\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: CENTER;\">\n<div style=\"font-style: italic;font-size: 19px; color: #FF0000; font-weight: bold\"><u><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/home\/quick-class-anemias-aulas-rapidas-de-3-a-8-minutos\/\">*CLIQUE AQUI PARA ASSISTIR TODAS AS AULAS !*<\/u><\/a><\/div>\n<\/div>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p><!--\nparte 6\n--><\/p>\n<div style=\"text-align: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/img_cientificas_menu1.png\" alt=\"img_cientificas_menu1\" width=\"696\" height=\"60\" class=\"alignnone size-full wp-image-5729\" srcset=\"https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/img_cientificas_menu1.png 696w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/img_cientificas_menu1-300x26.png 300w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/img_cientificas_menu1-500x43.png 500w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/img_cientificas_menu1-250x22.png 250w, https:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/img_cientificas_menu1-680x59.png 680w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/>\n<\/div>\n<div style=\"text-align: center;\">\n<iframe loading=\"lazy\" width=\"700\" height=\"455\" src=\"https:\/\/www.youtube.com\/embed\/yWA93ip65KU\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div>\n<p>&nbsp;<\/p>\n<p><!--\nparte 7 novo\n--><\/p>\n<div style=\"text-align: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/conheca-academia-ciencia-tecnologia.png\" alt=\"conheca-academia-ciencia-tecnologia\" width=\"950\" height=\"56\" class=\"alignnone size-full wp-image-4937\" \/>\n<\/div>\n<div style=\"text-align: left;\">\n[ezcol_1third]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/dependencias-academia.jpg\" alt=\"dependencias-academia\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-4938\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/act\/\">HIST\u00d3RIA E DEPEND\u00caNCIAS F\u00cdSICAS<\/a><\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third]<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/05\/mosaico.png\" alt=\"mosaico\" width=\"300\" height=\"158\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"http:\/\/www.ciencianews.com.br\/index.php\/fotos-das-turmas\/\" target=\"_blank\">NOMES E FOTOS DE TURMAS CERTIFICADAS <\/a><\/div>\n<p>[\/ezcol_1third]<br \/>\n[ezcol_1third_end]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/09\/AULA-ACADEMIA.png\" alt=\"AULA-ACADEMIA\" width=\"300\" height=\"158\" class=\"alignnone size-full wp-image-4939\" \/><\/p>\n<div style=\"color: #000000; text-align: left; font-size: 15px; font-weight: bold;\"><a href=\"https:\/\/www.youtube.com\/embed\/_4qONCahX3g\" target=\"_blank\">UM DIA DE AULA NA ACADEMIA<\/a><\/div>\n<p>[\/ezcol_1third_end]\n<\/p><\/div>\n<p><!--\nparte 7\n--><\/p>\n<div style=\"text-align: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/11\/Link_Parceiros.png\" alt=\"pos_img1\" width=\"180\" height=\"42\" \/>\n<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\">\n[ezcol_1third]<br \/>\n<a href=\"http:\/\/hemoglobinopatias.com.br\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\"  src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/11\/btn_hemo.png\" alt=\"pos_img1\" width=\"180\" height=\"32\" \/><\/a><br \/>\n<a href=\"http:\/\/www.talassemias.com.br\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\"  src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/11\/btn_tala.png\" alt=\"pos_img1\" width=\"180\" height=\"32\" \/><\/a><br \/>\n[\/ezcol_1third]<br \/>\n[ezcol_1third]<br \/>\n<a href=\"http:\/\/www.biologiadocancer.com.br\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\"  src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/11\/btn_bio.png\" alt=\"pos_img1\" width=\"180\" height=\"32\" \/><\/a><br \/>\n<a href=\"http:\/\/www.institutonaoum.com.br\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\"  src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2016\/11\/btn_inst.png\" alt=\"pos_img1\" width=\"180\" height=\"32\" \/><br \/>\n[\/ezcol_1third]<br \/>\n[ezcol_1third_end]<br \/>\n<a href=\"http:\/\/www.cdalab.com.br\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\"  src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/02\/btn_cda_lab.png\" alt=\"btn_cda_lab\" width=\"180\" height=\"32\" \/><\/a><br \/>\n<a href=\"http:\/\/faceres.com.br\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\"  src=\"http:\/\/www.ciencianews.com.br\/wp-content\/uploads\/2017\/02\/btn_faceres.png\" alt=\"btn_faceres\" width=\"180\" height=\"32\" \/><\/a><br \/>\n[\/ezcol_1third_end]\n<\/div>\n<div style=\"text-align: center;\">\n<div style=\"color: #000000; font-size: 25px;font-weight: bold;\">Academia de Ci\u00eancia e Tecnologia<\/div>\n<div style=\"color: #000000;  font-size: 17px;\">E-mail: a.c.t@terra.com.br<\/div>\n<div style=\"color: #000000;  font-size: 17px;\">Telefone (Phone): (55 17) 3233-4490<\/div>\n<div style=\"color: #000000;  font-size: 17px;\">Endere\u00e7o (Address): Rua Bonf\u00e1 Natale,1860<\/div>\n<div style=\"color: #000000;  font-size: 17px;\">CEP (Zip Code): 15020-130 &#8211; S\u00e3o Jos\u00e9 do Rio Preto,SP.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Academia de Ci\u00eancia e Tecnologia Instituto de P\u00f3s Gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas e Hematol\u00f3gicas Cursos de P\u00f3s Gradua\u00e7\u00e3o Lato-Sensu Conte\u00fado de responsabilidade dos idealizadores: Diretor Cient\u00edfico: Prof. Dr. Paulo Cesar Naoum Diretor Cl\u00ednico: Prof .Dr. Flavio Augusto Naoum Diretora Pedag\u00f3gica: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","_joinchat":[],"footnotes":""},"class_list":["post-3898","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false,"business-hub-blog":false,"business-hub-work":false},"uagb_author_info":{"display_name":"real","author_link":"https:\/\/www.ciencianews.com.br\/index.php\/author\/real\/"},"uagb_comment_info":0,"uagb_excerpt":"Academia de Ci\u00eancia e Tecnologia Instituto de P\u00f3s Gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas e Hematol\u00f3gicas Cursos de P\u00f3s Gradua\u00e7\u00e3o Lato-Sensu Conte\u00fado de responsabilidade dos idealizadores: Diretor Cient\u00edfico: Prof. Dr. Paulo Cesar Naoum Diretor Cl\u00ednico: Prof .Dr. Flavio Augusto Naoum Diretora Pedag\u00f3gica: [&hellip;]","_links":{"self":[{"href":"https:\/\/www.ciencianews.com.br\/index.php\/wp-json\/wp\/v2\/pages\/3898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ciencianews.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ciencianews.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ciencianews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ciencianews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3898"}],"version-history":[{"count":113,"href":"https:\/\/www.ciencianews.com.br\/index.php\/wp-json\/wp\/v2\/pages\/3898\/revisions"}],"predecessor-version":[{"id":6156,"href":"https:\/\/www.ciencianews.com.br\/index.php\/wp-json\/wp\/v2\/pages\/3898\/revisions\/6156"}],"wp:attachment":[{"href":"https:\/\/www.ciencianews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}